{"id":11849,"date":"2025-10-21T13:00:00","date_gmt":"2025-10-21T13:00:00","guid":{"rendered":"https:\/\/eperi.com\/?p=11849"},"modified":"2025-09-04T11:54:17","modified_gmt":"2025-09-04T11:54:17","slug":"quantenresistenz","status":"publish","type":"post","link":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/","title":{"rendered":"Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11849\" class=\"elementor elementor-11849\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-936024a e-flex e-con-boxed e-con e-parent\" data-id=\"936024a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf883d6 elementor-widget elementor-widget-tertiaryStage\" data-id=\"bf883d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tertiaryStage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tertiaryStage top_padding_56 \">\n\t\t\t<div>\n\t\t\t\t\t\t\t\t<h1 class=\"title_size_1 top_margin_12 teaserHeadline\">Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen<\/h1>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"top_margin_40 teaser-wrapper\">\n\t\t\t\t<div class=\"style-element\">\n\t\t\t\t\t<div class=\"copy_medium\" style=\"width:100%; max-width:450px\">Quantencomputer ver\u00e4ndern die Spielregeln der IT-Sicherheit \u2013 klassische Verfahren wie RSA oder ECC werden angreifbar. Post-Quantum Cryptography (PQC) bietet Unternehmen die Chance, ihre Daten schon heute zukunftssicher zu verschl\u00fcsseln und regulatorische Anforderungen wie DORA oder NIS2 einzuhalten.<\/div>\n\t\t\t\t\t<div class=\"top_margin_24 stageLinks\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div style=\"position:absolute; top:0px; left:0px; background-color:#00B4B4; width:4px; height:24px; border-radius: 0 0 4px 0\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"teaserImage\">\n\t\t\t\t<div><img decoding=\"async\" src=\"https:\/\/eperi.com\/wp-content\/uploads\/2024\/04\/Graphic.png\" alt=\"\" class=\"default_image border_radius_24\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-066a4da e-flex e-con-boxed e-con e-parent\" data-id=\"066a4da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0841647 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0841647\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9805088 e-con-full e-flex e-con e-child\" data-id=\"9805088\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55df0c7 elementor-widget elementor-widget-post-info\" data-id=\"55df0c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-7065232 elementor-inline-item\" itemprop=\"author\">\n\t\t\t\t\t\t<a href=\"https:\/\/eperi.com\/de\/author\/ricardo-izzieperi-com\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pen-nib\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t\t\t\tRicardo Izzi\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-432626c elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/eperi.com\/de\/2025\/10\/21\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-calendar-alt\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>Oktober 21, 2025<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-391e0d6 elementor-inline-item\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tags\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<a href=\"https:\/\/eperi.com\/de\/category\/newsroom\/blog\/\" class=\"elementor-post-info__terms-list-item\">blog<\/a>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d180988 elementor-widget elementor-widget-betterdocs-reading-time\" data-id=\"d180988\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"betterdocs-reading-time.default\">\n\t\t\t\t\t<div class=\"reading-time betterdocs\">\n\t<p>\n\t\t<svg width=\"14\" viewBox=\"0 0 14 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t<mask id=\"mask0_6195_23752\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\">\n\t\t\t<rect y=\"0.5\" width=\"14\" height=\"14\" fill=\"#D9D9D9\"\/>\n\t\t\t<\/mask>\n\t\t\t<g mask=\"url(#mask0_6195_23752)\">\n\t\t\t<path d=\"M8.92508 10.241L9.74175 9.42435L7.58341 7.26602V4.58268H6.41675V7.73268L8.92508 10.241ZM7.00008 13.3327C6.19314 13.3327 5.4348 13.1796 4.72508 12.8733C4.01536 12.5671 3.398 12.1514 2.873 11.6264C2.348 11.1014 1.93237 10.4841 1.62612 9.77435C1.31987 9.06463 1.16675 8.30629 1.16675 7.49935C1.16675 6.6924 1.31987 5.93407 1.62612 5.22435C1.93237 4.51463 2.348 3.89727 2.873 3.37227C3.398 2.84727 4.01536 2.43164 4.72508 2.12539C5.4348 1.81914 6.19314 1.66602 7.00008 1.66602C7.80703 1.66602 8.56536 1.81914 9.27508 2.12539C9.9848 2.43164 10.6022 2.84727 11.1272 3.37227C11.6522 3.89727 12.0678 4.51463 12.374 5.22435C12.6803 5.93407 12.8334 6.6924 12.8334 7.49935C12.8334 8.30629 12.6803 9.06463 12.374 9.77435C12.0678 10.4841 11.6522 11.1014 11.1272 11.6264C10.6022 12.1514 9.9848 12.5671 9.27508 12.8733C8.56536 13.1796 7.80703 13.3327 7.00008 13.3327ZM7.00008 12.166C8.29314 12.166 9.39418 11.7115 10.3032 10.8025C11.2122 9.89345 11.6667 8.7924 11.6667 7.49935C11.6667 6.20629 11.2122 5.10525 10.3032 4.19622C9.39418 3.2872 8.29314 2.83268 7.00008 2.83268C5.70703 2.83268 4.60598 3.2872 3.69696 4.19622C2.78793 5.10525 2.33341 6.20629 2.33341 7.49935C2.33341 8.7924 2.78793 9.89345 3.69696 10.8025C4.60598 11.7115 5.70703 12.166 7.00008 12.166Z\" fill=\"#667085\"\/>\n\t\t\t<\/g>\n\t\t<\/svg>\n\t\t3 min\t<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffc66b5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ffc66b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cc01c0 e-flex e-con-boxed e-con e-parent\" data-id=\"3cc01c0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8b4083c e-con-full e-flex e-con e-child\" data-id=\"8b4083c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bff4b87 elementor-widget elementor-widget-richText\" data-id=\"bff4b87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"richText.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <style>\n            .customBulletList ol {\n                list-style-type: decimal;\n                padding-left: 30px;\n            }\n\n            .customBulletList ol li {\n                padding-left: 5px;\n                margin-bottom: 16px;\n\n            }\n\n            .customBulletList ul {\n                list-style: none;\n                padding-left: 0;\n            }\n\n            .customBulletList ul li {\n                display: flex;\n                align-items: start;\n                gap: 30px;\n                margin-bottom: 16px;\n            }\n\n            .customBulletList ul li .listIcon {\n                width: 24px;\n                height: 24px;\n\n            }\n\n            .customBulletList ul li svg {\n                width: 24px !important;\n                fill: #00B4B4;\n                margin-top: 0px;\n\n            }\n\n            .customBulletList ol li .listIcon {\n                display: none !important\n            }\n\n            .customBulletList li a {\n                display: inline-flex !important;\n                text-decoration: underline !important;\n                color: #00B4B4;\n            }\n\n            .richText a {\n                color: #00B4B4;\n                text-decoration: underline;\n            }\n\n            .richText p {\n                margin: 0;\n                margin-bottom: 20px;\n            }\n\n            .richText p:last-child {\n                margin-bottom: 0 !important;\n            }\n        <\/style>\n        <div class=\"richText customBulletList copy_medium text-color\"><h2>Post-Quantum Cryptography: Wie Unternehmen sich jetzt absichern<\/h2><p><br \/>Quantencomputer stellen klassische Verschl\u00fcsselungsverfahren wie RSA, ECC oder DSA infrage. Viele dieser Algorithmen, heute noch Standard, k\u00f6nnten in wenigen Jahren durch Quantenrechner gebrochen werden. Die L\u00f6sung: Post-Quantum Cryptography (PQC) \u2013 quantensichere Algorithmen, die gegen zuk\u00fcnftige Quantenangriffe resistent sind.<\/p><p>Wir schauen uns das Thema in unserer Cybersecurity Academy im Rahmen des Cybersecurity Awareness Month einmal genauer an.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b074211 elementor-widget elementor-widget-richText\" data-id=\"b074211\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"richText.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <style>\n            .customBulletList ol {\n                list-style-type: decimal;\n                padding-left: 30px;\n            }\n\n            .customBulletList ol li {\n                padding-left: 5px;\n                margin-bottom: 16px;\n\n            }\n\n            .customBulletList ul {\n                list-style: none;\n                padding-left: 0;\n            }\n\n            .customBulletList ul li {\n                display: flex;\n                align-items: start;\n                gap: 30px;\n                margin-bottom: 16px;\n            }\n\n            .customBulletList ul li .listIcon {\n                width: 24px;\n                height: 24px;\n\n            }\n\n            .customBulletList ul li svg {\n                width: 24px !important;\n                fill: #00B4B4;\n                margin-top: 0px;\n\n            }\n\n            .customBulletList ol li .listIcon {\n                display: none !important\n            }\n\n            .customBulletList li a {\n                display: inline-flex !important;\n                text-decoration: underline !important;\n                color: #00B4B4;\n            }\n\n            .richText a {\n                color: #00B4B4;\n                text-decoration: underline;\n            }\n\n            .richText p {\n                margin: 0;\n                margin-bottom: 20px;\n            }\n\n            .richText p:last-child {\n                margin-bottom: 0 !important;\n            }\n        <\/style>\n        <div class=\"richText customBulletList copy_medium text-color\"><h2>Was ist Post-Quantum Cryptography (PQC)?<\/h2><p><br \/>PQC beschreibt eine neue Generation von Verschl\u00fcsselungsverfahren, die gezielt gegen mathematische Angriffe durch Quantencomputer entwickelt wurden. Ziel ist es, bew\u00e4hrte Algorithmen wie RSA, ECC oder Diffie-Hellman durch quantenresistente Alternativen wie Kyber oder Dilithium zu ersetzen.<\/p><p><strong>Relevante Akteure und Standards:<\/strong><\/p><ul><li><div class=\"listIcon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5c1f5060-c79f-455b-951c-fdfba722c0a4\" data-name=\"Ebene 1\" viewBox=\"0 0 18 18\"><defs><style>      .uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1 {        stroke-width: 0px;      }    <\/style><\/defs><path class=\"uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1\" d=\"m17.15,8.14h-7.29s0-7.29,0-7.29c0-.22-.09-.44-.26-.6-.16-.16-.38-.25-.6-.25h0c-.23,0-.45.09-.61.25-.16.16-.25.38-.25.61v7.29H.86c-.23,0-.44.09-.6.25-.16.16-.25.38-.25.61,0,.23.09.44.25.6.16.16.38.25.61.25h7.29s0,7.29,0,7.29c0,.47.38.85.86.85.23,0,.44-.09.61-.25s.25-.38.25-.6v-7.29s7.29,0,7.29,0c.23,0,.44-.09.61-.25s.25-.38.25-.61c0-.47-.38-.85-.85-.85Z\"><\/path><\/svg><\/div>NIST: F\u00fchrt die Standardisierung von PQC-Verfahren an (z.\u202fB. Kyber, Dilithium, SPHINCS+)<\/li><li><div class=\"listIcon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5c1f5060-c79f-455b-951c-fdfba722c0a4\" data-name=\"Ebene 1\" viewBox=\"0 0 18 18\"><defs><style>      .uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1 {        stroke-width: 0px;      }    <\/style><\/defs><path class=\"uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1\" d=\"m17.15,8.14h-7.29s0-7.29,0-7.29c0-.22-.09-.44-.26-.6-.16-.16-.38-.25-.6-.25h0c-.23,0-.45.09-.61.25-.16.16-.25.38-.25.61v7.29H.86c-.23,0-.44.09-.6.25-.16.16-.25.38-.25.61,0,.23.09.44.25.6.16.16.38.25.61.25h7.29s0,7.29,0,7.29c0,.47.38.85.86.85.23,0,.44-.09.61-.25s.25-.38.25-.6v-7.29s7.29,0,7.29,0c.23,0,.44-.09.61-.25s.25-.38.25-.61c0-.47-.38-.85-.85-.85Z\"><\/path><\/svg><\/div>BSI: Gibt Empfehlungen zur PQC-Readiness f\u00fcr deutsche Unternehmen<\/li><li><div class=\"listIcon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5c1f5060-c79f-455b-951c-fdfba722c0a4\" data-name=\"Ebene 1\" viewBox=\"0 0 18 18\"><defs><style>      .uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1 {        stroke-width: 0px;      }    <\/style><\/defs><path class=\"uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1\" d=\"m17.15,8.14h-7.29s0-7.29,0-7.29c0-.22-.09-.44-.26-.6-.16-.16-.38-.25-.6-.25h0c-.23,0-.45.09-.61.25-.16.16-.25.38-.25.61v7.29H.86c-.23,0-.44.09-.6.25-.16.16-.25.38-.25.61,0,.23.09.44.25.6.16.16.38.25.61.25h7.29s0,7.29,0,7.29c0,.47.38.85.86.85.23,0,.44-.09.61-.25s.25-.38.25-.6v-7.29s7.29,0,7.29,0c.23,0,.44-.09.61-.25s.25-.38.25-.61c0-.47-.38-.85-.85-.85Z\"><\/path><\/svg><\/div>EU \/ DORA: Fordern quantensichere Kryptografie bei regulierten Unternehmen in Finanz-, Energie- und Infrastruktursektoren<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c689717 elementor-widget elementor-widget-richText\" data-id=\"c689717\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"richText.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <style>\n            .customBulletList ol {\n                list-style-type: decimal;\n                padding-left: 30px;\n            }\n\n            .customBulletList ol li {\n                padding-left: 5px;\n                margin-bottom: 16px;\n\n            }\n\n            .customBulletList ul {\n                list-style: none;\n                padding-left: 0;\n            }\n\n            .customBulletList ul li {\n                display: flex;\n                align-items: start;\n                gap: 30px;\n                margin-bottom: 16px;\n            }\n\n            .customBulletList ul li .listIcon {\n                width: 24px;\n                height: 24px;\n\n            }\n\n            .customBulletList ul li svg {\n                width: 24px !important;\n                fill: #00B4B4;\n                margin-top: 0px;\n\n            }\n\n            .customBulletList ol li .listIcon {\n                display: none !important\n            }\n\n            .customBulletList li a {\n                display: inline-flex !important;\n                text-decoration: underline !important;\n                color: #00B4B4;\n            }\n\n            .richText a {\n                color: #00B4B4;\n                text-decoration: underline;\n            }\n\n            .richText p {\n                margin: 0;\n                margin-bottom: 20px;\n            }\n\n            .richText p:last-child {\n                margin-bottom: 0 !important;\n            }\n        <\/style>\n        <div class=\"richText customBulletList copy_medium text-color\"><h2>Warum jetzt auf PQC umstellen \u2013 nicht sp\u00e4ter<\/h2><p><br \/>Die Risiken sind real \u2013 und wachsen mit jeder Innovation im Quantencomputing:<\/p><ul><li><div class=\"listIcon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5c1f5060-c79f-455b-951c-fdfba722c0a4\" data-name=\"Ebene 1\" viewBox=\"0 0 18 18\"><defs><style>      .uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1 {        stroke-width: 0px;      }    <\/style><\/defs><path class=\"uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1\" d=\"m17.15,8.14h-7.29s0-7.29,0-7.29c0-.22-.09-.44-.26-.6-.16-.16-.38-.25-.6-.25h0c-.23,0-.45.09-.61.25-.16.16-.25.38-.25.61v7.29H.86c-.23,0-.44.09-.6.25-.16.16-.25.38-.25.61,0,.23.09.44.25.6.16.16.38.25.61.25h7.29s0,7.29,0,7.29c0,.47.38.85.86.85.23,0,.44-.09.61-.25s.25-.38.25-.6v-7.29s7.29,0,7.29,0c.23,0,.44-.09.61-.25s.25-.38.25-.61c0-.47-.38-.85-.85-.85Z\"><\/path><\/svg><\/div>Harvest now, decrypt later: Angreifer speichern heute verschl\u00fcsselte Daten, um sie sp\u00e4ter mit Quantenrechnern zu entschl\u00fcsseln<\/li><li><div class=\"listIcon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5c1f5060-c79f-455b-951c-fdfba722c0a4\" data-name=\"Ebene 1\" viewBox=\"0 0 18 18\"><defs><style>      .uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1 {        stroke-width: 0px;      }    <\/style><\/defs><path class=\"uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1\" d=\"m17.15,8.14h-7.29s0-7.29,0-7.29c0-.22-.09-.44-.26-.6-.16-.16-.38-.25-.6-.25h0c-.23,0-.45.09-.61.25-.16.16-.25.38-.25.61v7.29H.86c-.23,0-.44.09-.6.25-.16.16-.25.38-.25.61,0,.23.09.44.25.6.16.16.38.25.61.25h7.29s0,7.29,0,7.29c0,.47.38.85.86.85.23,0,.44-.09.61-.25s.25-.38.25-.6v-7.29s7.29,0,7.29,0c.23,0,.44-.09.61-.25s.25-.38.25-.61c0-.47-.38-.85-.85-.85Z\"><\/path><\/svg><\/div>Langfristiger Umstellungsbedarf: PQC-Migration betrifft Systeme, Schl\u00fcssel, Zertifikate, Applikationen \u2013 eine mehrj\u00e4hrige Aufgabe<\/li><li><div class=\"listIcon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5c1f5060-c79f-455b-951c-fdfba722c0a4\" data-name=\"Ebene 1\" viewBox=\"0 0 18 18\"><defs><style>      .uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1 {        stroke-width: 0px;      }    <\/style><\/defs><path class=\"uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1\" d=\"m17.15,8.14h-7.29s0-7.29,0-7.29c0-.22-.09-.44-.26-.6-.16-.16-.38-.25-.6-.25h0c-.23,0-.45.09-.61.25-.16.16-.25.38-.25.61v7.29H.86c-.23,0-.44.09-.6.25-.16.16-.25.38-.25.61,0,.23.09.44.25.6.16.16.38.25.61.25h7.29s0,7.29,0,7.29c0,.47.38.85.86.85.23,0,.44-.09.61-.25s.25-.38.25-.6v-7.29s7.29,0,7.29,0c.23,0,.44-.09.61-.25s.25-.38.25-.61c0-.47-.38-.85-.85-.85Z\"><\/path><\/svg><\/div>Regulatorischer Druck: Verordnungen wie DORA, NIS2 oder das BSI IT-Grundschutz-Kompendium verlangen belastbare kryptografische Transitionen<\/li><\/ul><p><strong>Fazit:<\/strong> Wer erst bei Marktreife von Quantencomputern reagiert, reagiert zu sp\u00e4t.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-747c1e0 elementor-widget elementor-widget-richText\" data-id=\"747c1e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"richText.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <style>\n            .customBulletList ol {\n                list-style-type: decimal;\n                padding-left: 30px;\n            }\n\n            .customBulletList ol li {\n                padding-left: 5px;\n                margin-bottom: 16px;\n\n            }\n\n            .customBulletList ul {\n                list-style: none;\n                padding-left: 0;\n            }\n\n            .customBulletList ul li {\n                display: flex;\n                align-items: start;\n                gap: 30px;\n                margin-bottom: 16px;\n            }\n\n            .customBulletList ul li .listIcon {\n                width: 24px;\n                height: 24px;\n\n            }\n\n            .customBulletList ul li svg {\n                width: 24px !important;\n                fill: #00B4B4;\n                margin-top: 0px;\n\n            }\n\n            .customBulletList ol li .listIcon {\n                display: none !important\n            }\n\n            .customBulletList li a {\n                display: inline-flex !important;\n                text-decoration: underline !important;\n                color: #00B4B4;\n            }\n\n            .richText a {\n                color: #00B4B4;\n                text-decoration: underline;\n            }\n\n            .richText p {\n                margin: 0;\n                margin-bottom: 20px;\n            }\n\n            .richText p:last-child {\n                margin-bottom: 0 !important;\n            }\n        <\/style>\n        <div class=\"richText customBulletList copy_medium text-color\"><h2>eperi QuantumEdge: PQC-Readiness jetzt strategisch angehen<\/h2><p><br \/><strong>QuantumEdge<\/strong> ist das spezialisierte Erweiterungsmodul der <strong>eperi\u00ae sEcure Plattform<\/strong>. Es unterst\u00fctzt Unternehmen bei der kontrollierten, regulatorisch konformen und technisch reibungslosen Einf\u00fchrung quantensicherer Verschl\u00fcsselung.<\/p><p><strong>Funktionen im \u00dcberblick:<\/strong><\/p><table><thead><tr><td><p><strong>Funktion<\/strong><\/p><\/td><td><p><strong>Beschreibung<\/strong><\/p><\/td><\/tr><\/thead><tbody><tr><td><p>Kryptografie-Scan<\/p><\/td><td><p>Analyse aller eingesetzten Verschl\u00fcsselungsverfahren<\/p><\/td><\/tr><tr><td><p>Schatten-IT-Erkennung<\/p><\/td><td><p>Aufdeckung unsicherer Systeme und veralteter Algorithmen<\/p><\/td><\/tr><tr><td><p>Hybride TLS-Verschl\u00fcsselung<\/p><\/td><td><p>Gleichzeitiger Einsatz klassischer und PQC-basierter Algorithmen<\/p><\/td><\/tr><tr><td><p>PQC-Dashboard<\/p><\/td><td><p>\u00dcbersicht \u00fcber Systeme, Endpunkte und Migrationsstatus<\/p><\/td><\/tr><tr><td><p>Policy Engine<\/p><\/td><td><p>Regelbasierte Steuerung der PQC-Einf\u00fchrung<\/p><\/td><\/tr><tr><td><p>Infrastruktur-Integration<\/p><\/td><td><p>Kompatibel mit KMS, Zertifikats- und Identity-Systemen<\/p><\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><h3>Migration ohne Disruption<\/h3><p><br \/>QuantumEdge erm\u00f6glicht einen hybriden Migrationspfad \u2013 Post-Quantum-Verfahren werden parallel zu klassischen Algorithmen eingef\u00fchrt. Kritische Systeme lassen sich priorisieren, w\u00e4hrend nicht-kritische Komponenten sukzessive umgestellt werden. So bleibt die Systemlandschaft jederzeit verf\u00fcgbar und funktionsf\u00e4hig.<\/p><p><strong>Vorteile mit QuantumEdge auf einen Blick<\/strong><\/p><ul><li><div class=\"listIcon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5c1f5060-c79f-455b-951c-fdfba722c0a4\" data-name=\"Ebene 1\" viewBox=\"0 0 18 18\"><defs><style>      .uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1 {        stroke-width: 0px;      }    <\/style><\/defs><path class=\"uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1\" d=\"m17.15,8.14h-7.29s0-7.29,0-7.29c0-.22-.09-.44-.26-.6-.16-.16-.38-.25-.6-.25h0c-.23,0-.45.09-.61.25-.16.16-.25.38-.25.61v7.29H.86c-.23,0-.44.09-.6.25-.16.16-.25.38-.25.61,0,.23.09.44.25.6.16.16.38.25.61.25h7.29s0,7.29,0,7.29c0,.47.38.85.86.85.23,0,.44-.09.61-.25s.25-.38.25-.6v-7.29s7.29,0,7.29,0c.23,0,.44-.09.61-.25s.25-.38.25-.61c0-.47-.38-.85-.85-.85Z\"><\/path><\/svg><\/div>Zukunftssichere Kryptografie gegen Quantenangriffe<\/li><li><div class=\"listIcon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5c1f5060-c79f-455b-951c-fdfba722c0a4\" data-name=\"Ebene 1\" viewBox=\"0 0 18 18\"><defs><style>      .uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1 {        stroke-width: 0px;      }    <\/style><\/defs><path class=\"uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1\" d=\"m17.15,8.14h-7.29s0-7.29,0-7.29c0-.22-.09-.44-.26-.6-.16-.16-.38-.25-.6-.25h0c-.23,0-.45.09-.61.25-.16.16-.25.38-.25.61v7.29H.86c-.23,0-.44.09-.6.25-.16.16-.25.38-.25.61,0,.23.09.44.25.6.16.16.38.25.61.25h7.29s0,7.29,0,7.29c0,.47.38.85.86.85.23,0,.44-.09.61-.25s.25-.38.25-.6v-7.29s7.29,0,7.29,0c.23,0,.44-.09.61-.25s.25-.38.25-.61c0-.47-.38-.85-.85-.85Z\"><\/path><\/svg><\/div>Transparenz \u00fcber kryptografische Risiken und Schwachstellen<\/li><li><div class=\"listIcon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5c1f5060-c79f-455b-951c-fdfba722c0a4\" data-name=\"Ebene 1\" viewBox=\"0 0 18 18\"><defs><style>      .uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1 {        stroke-width: 0px;      }    <\/style><\/defs><path class=\"uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1\" d=\"m17.15,8.14h-7.29s0-7.29,0-7.29c0-.22-.09-.44-.26-.6-.16-.16-.38-.25-.6-.25h0c-.23,0-.45.09-.61.25-.16.16-.25.38-.25.61v7.29H.86c-.23,0-.44.09-.6.25-.16.16-.25.38-.25.61,0,.23.09.44.25.6.16.16.38.25.61.25h7.29s0,7.29,0,7.29c0,.47.38.85.86.85.23,0,.44-.09.61-.25s.25-.38.25-.6v-7.29s7.29,0,7.29,0c.23,0,.44-.09.61-.25s.25-.38.25-.61c0-.47-.38-.85-.85-.85Z\"><\/path><\/svg><\/div>Konforme Umsetzung nach NIST-, BSI- und EU-Vorgaben (DORA, NIS2)<\/li><li><div class=\"listIcon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5c1f5060-c79f-455b-951c-fdfba722c0a4\" data-name=\"Ebene 1\" viewBox=\"0 0 18 18\"><defs><style>      .uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1 {        stroke-width: 0px;      }    <\/style><\/defs><path class=\"uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1\" d=\"m17.15,8.14h-7.29s0-7.29,0-7.29c0-.22-.09-.44-.26-.6-.16-.16-.38-.25-.6-.25h0c-.23,0-.45.09-.61.25-.16.16-.25.38-.25.61v7.29H.86c-.23,0-.44.09-.6.25-.16.16-.25.38-.25.61,0,.23.09.44.25.6.16.16.38.25.61.25h7.29s0,7.29,0,7.29c0,.47.38.85.86.85.23,0,.44-.09.61-.25s.25-.38.25-.6v-7.29s7.29,0,7.29,0c.23,0,.44-.09.61-.25s.25-.38.25-.61c0-.47-.38-.85-.85-.85Z\"><\/path><\/svg><\/div>Einfache Integration in bestehende Infrastruktur<\/li><li><div class=\"listIcon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"uuid-5c1f5060-c79f-455b-951c-fdfba722c0a4\" data-name=\"Ebene 1\" viewBox=\"0 0 18 18\"><defs><style>      .uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1 {        stroke-width: 0px;      }    <\/style><\/defs><path class=\"uuid-07fe4fd6-62f4-4301-bf52-28d26aeefbf1\" d=\"m17.15,8.14h-7.29s0-7.29,0-7.29c0-.22-.09-.44-.26-.6-.16-.16-.38-.25-.6-.25h0c-.23,0-.45.09-.61.25-.16.16-.25.38-.25.61v7.29H.86c-.23,0-.44.09-.6.25-.16.16-.25.38-.25.61,0,.23.09.44.25.6.16.16.38.25.61.25h7.29s0,7.29,0,7.29c0,.47.38.85.86.85.23,0,.44-.09.61-.25s.25-.38.25-.6v-7.29s7.29,0,7.29,0c.23,0,.44-.09.61-.25s.25-.38.25-.61c0-.47-.38-.85-.85-.85Z\"><\/path><\/svg><\/div>Strategisch steuerbare PQC-Roadmap inklusive Auditf\u00e4higkeit<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03390a5 elementor-widget elementor-widget-richText\" data-id=\"03390a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"richText.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <style>\n            .customBulletList ol {\n                list-style-type: decimal;\n                padding-left: 30px;\n            }\n\n            .customBulletList ol li {\n                padding-left: 5px;\n                margin-bottom: 16px;\n\n            }\n\n            .customBulletList ul {\n                list-style: none;\n                padding-left: 0;\n            }\n\n            .customBulletList ul li {\n                display: flex;\n                align-items: start;\n                gap: 30px;\n                margin-bottom: 16px;\n            }\n\n            .customBulletList ul li .listIcon {\n                width: 24px;\n                height: 24px;\n\n            }\n\n            .customBulletList ul li svg {\n                width: 24px !important;\n                fill: #00B4B4;\n                margin-top: 0px;\n\n            }\n\n            .customBulletList ol li .listIcon {\n                display: none !important\n            }\n\n            .customBulletList li a {\n                display: inline-flex !important;\n                text-decoration: underline !important;\n                color: #00B4B4;\n            }\n\n            .richText a {\n                color: #00B4B4;\n                text-decoration: underline;\n            }\n\n            .richText p {\n                margin: 0;\n                margin-bottom: 20px;\n            }\n\n            .richText p:last-child {\n                margin-bottom: 0 !important;\n            }\n        <\/style>\n        <div class=\"richText customBulletList copy_medium text-color\"><h2>FAQ: H\u00e4ufige Fragen zur Post-Quantum Cryptography<\/h2><p><br \/><strong>Ist PQC bereits verpflichtend?<\/strong><br \/>Noch nicht fl\u00e4chendeckend. Aber DORA, BSI und NIS2 fordern bereits jetzt konkrete Ma\u00dfnahmen f\u00fcr kritische Infrastrukturen und Finanzdienstleister.<\/p><p><strong>Warum reicht hybride Verschl\u00fcsselung zun\u00e4chst aus?<\/strong><br \/>Sie erlaubt den Parallelbetrieb von klassischen und PQC-Algorithmen \u2013 ideal f\u00fcr risikobasierte Migrationsstrategien ohne Funktionsverluste.<\/p><p><strong>Wie lange dauert eine PQC-Umstellung?<\/strong><br \/>Je nach Systemlandschaft mehrere Jahre. Je fr\u00fcher Unternehmen beginnen, desto besser lassen sich regulatorische Deadlines einhalten.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f206c7 e-con-full e-flex e-con e-child\" data-id=\"5f206c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24eae4f elementor-widget elementor-widget-richText\" data-id=\"24eae4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"richText.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <style>\n            .customBulletList ol {\n                list-style-type: decimal;\n                padding-left: 30px;\n            }\n\n            .customBulletList ol li {\n                padding-left: 5px;\n                margin-bottom: 16px;\n\n            }\n\n            .customBulletList ul {\n                list-style: none;\n                padding-left: 0;\n            }\n\n            .customBulletList ul li {\n                display: flex;\n                align-items: start;\n                gap: 30px;\n                margin-bottom: 16px;\n            }\n\n            .customBulletList ul li .listIcon {\n                width: 24px;\n                height: 24px;\n\n            }\n\n            .customBulletList ul li svg {\n                width: 24px !important;\n                fill: #00B4B4;\n                margin-top: 0px;\n\n            }\n\n            .customBulletList ol li .listIcon {\n                display: none !important\n            }\n\n            .customBulletList li a {\n                display: inline-flex !important;\n                text-decoration: underline !important;\n                color: #00B4B4;\n            }\n\n            .richText a {\n                color: #00B4B4;\n                text-decoration: underline;\n            }\n\n            .richText p {\n                margin: 0;\n                margin-bottom: 20px;\n            }\n\n            .richText p:last-child {\n                margin-bottom: 0 !important;\n            }\n        <\/style>\n        <div class=\"richText customBulletList copy_medium text-color\"><h2>Hat Ihnen dieser Artikel gefallen?<\/h2><p><br \/>Dann jetzt liken oder mit Kollegen, Gesch\u00e4ftspartnern sowie Freunden teilen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d133695 e-grid e-con-full e-con e-child\" data-id=\"d133695\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32c7b58 elementor-share-buttons--shape-rounded elementor-share-buttons--view-icon-text elementor-share-buttons--skin-gradient elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"32c7b58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Share on email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Share on facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Share on linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_x-twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Share on x-twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-x-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tX\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed53ce1 elementor-widget elementor-widget-shortcode\" data-id=\"ed53ce1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div class=\"wpulike wpulike-default \" ><div class=\"wp_ulike_general_class wp_ulike_is_restricted\"><button type=\"button\"\n\t\t\t\t\taria-label=\"Like Button\"\n\t\t\t\t\tdata-ulike-id=\"11849\"\n\t\t\t\t\tdata-ulike-nonce=\"6cf8fba466\"\n\t\t\t\t\tdata-ulike-type=\"post\"\n\t\t\t\t\tdata-ulike-template=\"wpulike-default\"\n\t\t\t\t\tdata-ulike-display-likers=\"0\"\n\t\t\t\t\tdata-ulike-likers-style=\"default\"\n\t\t\t\t\tclass=\"wp_ulike_btn wp_ulike_put_image wp_post_btn_11849\"><\/button><span class=\"count-box wp_ulike_counter_up\" data-ulike-counter-value=\"0\"><\/span>\t\t\t<\/div><\/div>\n\t\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59262833 e-flex e-con-boxed e-con e-parent\" data-id=\"59262833\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2b5cfda6 e-grid e-con-boxed e-con e-child\" data-id=\"2b5cfda6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-59c84c14 e-con-full e-flex e-con e-child\" data-id=\"59c84c14\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-216912f0 elementor-widget elementor-widget-h2\" data-id=\"216912f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"h2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <!-- <div style=\"background-color:red; color:white; display:inline; padding:0px 5px\">H2 Headline<\/div> -->\n        <h2 class=\"title_size_2 headline-color\">Wissen, das sch\u00fctzt \u2013 Ihre n\u00e4chste Ma\u00dfnahme f\u00fcr mehr Datensicherheit<\/h2>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e268cf7 elementor-widget elementor-widget-richText\" data-id=\"e268cf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"richText.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <style>\n            .customBulletList ol {\n                list-style-type: decimal;\n                padding-left: 30px;\n            }\n\n            .customBulletList ol li {\n                padding-left: 5px;\n                margin-bottom: 16px;\n\n            }\n\n            .customBulletList ul {\n                list-style: none;\n                padding-left: 0;\n            }\n\n            .customBulletList ul li {\n                display: flex;\n                align-items: start;\n                gap: 30px;\n                margin-bottom: 16px;\n            }\n\n            .customBulletList ul li .listIcon {\n                width: 24px;\n                height: 24px;\n\n            }\n\n            .customBulletList ul li svg {\n                width: 24px !important;\n                fill: #00B4B4;\n                margin-top: 0px;\n\n            }\n\n            .customBulletList ol li .listIcon {\n                display: none !important\n            }\n\n            .customBulletList li a {\n                display: inline-flex !important;\n                text-decoration: underline !important;\n                color: #00B4B4;\n            }\n\n            .richText a {\n                color: #00B4B4;\n                text-decoration: underline;\n            }\n\n            .richText p {\n                margin: 0;\n                margin-bottom: 20px;\n            }\n\n            .richText p:last-child {\n                margin-bottom: 0 !important;\n            }\n        <\/style>\n        <div class=\"richText customBulletList copy_medium text-color\"><p>Auf unserer Download-Seite finden Sie kostenlose Whitepaper und Factsheets zu Datenschutz, Datenverschl\u00fcsselung und Compliance \u2013 speziell f\u00fcr IT-Verantwortliche und Entscheider.<\/p><p>Erhalten Sie kompaktes Wissen, strategische Empfehlungen und praktische Tipps, um Ihre Daten effektiv zu sch\u00fctzen und regulatorische Vorgaben wie DSGVO, NIS2 und DORA sicher zu erf\u00fcllen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1897c014 elementor-widget elementor-widget-primaryButton\" data-id=\"1897c014\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"primaryButton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n                    <div class=\"button button_light_primary\">\n                                <a href=\"https:\/\/eperi.com\/de\/whitepaper-quantenbedrohung-voraus\/\" class=\"button_link\" id=\"\">\n                    Jetzt informieren &amp; kostenlos herunterladen                <\/a>\n            <\/div>\n        \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11b24f34 elementor-widget elementor-widget-image\" data-id=\"11b24f34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<!-- <div style=\"background-color:red; color:white; display:inline; padding:0px 5px\">Image<\/div> -->\n\t\t<img decoding=\"async\" src=\"https:\/\/eperi.com\/wp-content\/uploads\/2025\/04\/Whitepaper_Ganzheitliche_Cloud_Datenschutz_A4_Brochure_Mockup_2-scaled.webp\" alt=\"\" class=\"default_image border_radius_24\">\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Post-Quantum Cryptography (PQC) bezeichnet Verschl\u00fcsselungsverfahren, die resistent gegen\u00fcber Angriffen durch Quantencomputer sind. eperi QuantumEdge unterst\u00fctzt Unternehmen bei der schrittweisen Migration auf PQC durch Echtzeitanalyse der eingesetzten Kryptografie, hybride Verschl\u00fcsselung und zentrale Steuerung \u00fcber eine Policy Engine. Ziel ist die sichere und planbare Umsetzung quantensicherer Verschl\u00fcsselung gem\u00e4\u00df NIST, BSI und DORA.<\/p>\n","protected":false},"author":6,"featured_media":11832,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-11849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen<\/title>\n<meta name=\"description\" content=\"Quantenresistente Verschl\u00fcsselung mit eperi QuantumEdge \u2013 PQC-Readiness erkennen, planen und sicher umsetzen nach NIST, DORA und BSI.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen\" \/>\n<meta property=\"og:description\" content=\"Quantenresistente Verschl\u00fcsselung mit eperi QuantumEdge \u2013 PQC-Readiness erkennen, planen und sicher umsetzen nach NIST, DORA und BSI.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/\" \/>\n<meta property=\"og:site_name\" content=\"EPERI\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-21T13:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eperi.com\/wp-content\/uploads\/2025\/09\/Cybersecurity-academy-visual-blog-eperi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Izzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Izzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/\"},\"author\":{\"name\":\"Ricardo Izzi\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#\\\/schema\\\/person\\\/44a9b3a3f683b96f301707dfdd95fcff\"},\"headline\":\"Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen\",\"datePublished\":\"2025-10-21T13:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/\"},\"wordCount\":599,\"publisher\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Cybersecurity-academy-visual-blog-eperi.jpg\",\"articleSection\":[\"blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/\",\"url\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/\",\"name\":\"Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Cybersecurity-academy-visual-blog-eperi.jpg\",\"datePublished\":\"2025-10-21T13:00:00+00:00\",\"description\":\"Quantenresistente Verschl\u00fcsselung mit eperi QuantumEdge \u2013 PQC-Readiness erkennen, planen und sicher umsetzen nach NIST, DORA und BSI.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Cybersecurity-academy-visual-blog-eperi.jpg\",\"contentUrl\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Cybersecurity-academy-visual-blog-eperi.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/quantenresistenz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/eperi.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/eperi.com\\\/de\\\/\",\"name\":\"EPERI\",\"description\":\"Empower your Data. Keep control.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eperi.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#organization\",\"name\":\"EPERI\",\"url\":\"https:\\\/\\\/eperi.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-cropped-LogoEperi.png\",\"contentUrl\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-cropped-LogoEperi.png\",\"width\":512,\"height\":512,\"caption\":\"EPERI\"},\"image\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#\\\/schema\\\/person\\\/44a9b3a3f683b96f301707dfdd95fcff\",\"name\":\"Ricardo Izzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g\",\"caption\":\"Ricardo Izzi\"},\"url\":\"https:\\\/\\\/eperi.com\\\/de\\\/author\\\/ricardo-izzieperi-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen","description":"Quantenresistente Verschl\u00fcsselung mit eperi QuantumEdge \u2013 PQC-Readiness erkennen, planen und sicher umsetzen nach NIST, DORA und BSI.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/","og_locale":"de_DE","og_type":"article","og_title":"Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen","og_description":"Quantenresistente Verschl\u00fcsselung mit eperi QuantumEdge \u2013 PQC-Readiness erkennen, planen und sicher umsetzen nach NIST, DORA und BSI.","og_url":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/","og_site_name":"EPERI","article_published_time":"2025-10-21T13:00:00+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/eperi.com\/wp-content\/uploads\/2025\/09\/Cybersecurity-academy-visual-blog-eperi.jpg","type":"image\/jpeg"}],"author":"Ricardo Izzi","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Ricardo Izzi","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/#article","isPartOf":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/"},"author":{"name":"Ricardo Izzi","@id":"https:\/\/eperi.com\/de\/#\/schema\/person\/44a9b3a3f683b96f301707dfdd95fcff"},"headline":"Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen","datePublished":"2025-10-21T13:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/"},"wordCount":599,"publisher":{"@id":"https:\/\/eperi.com\/de\/#organization"},"image":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/#primaryimage"},"thumbnailUrl":"https:\/\/eperi.com\/wp-content\/uploads\/2025\/09\/Cybersecurity-academy-visual-blog-eperi.jpg","articleSection":["blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/","url":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/","name":"Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen","isPartOf":{"@id":"https:\/\/eperi.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/#primaryimage"},"image":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/#primaryimage"},"thumbnailUrl":"https:\/\/eperi.com\/wp-content\/uploads\/2025\/09\/Cybersecurity-academy-visual-blog-eperi.jpg","datePublished":"2025-10-21T13:00:00+00:00","description":"Quantenresistente Verschl\u00fcsselung mit eperi QuantumEdge \u2013 PQC-Readiness erkennen, planen und sicher umsetzen nach NIST, DORA und BSI.","breadcrumb":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/#primaryimage","url":"https:\/\/eperi.com\/wp-content\/uploads\/2025\/09\/Cybersecurity-academy-visual-blog-eperi.jpg","contentUrl":"https:\/\/eperi.com\/wp-content\/uploads\/2025\/09\/Cybersecurity-academy-visual-blog-eperi.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/quantenresistenz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/eperi.com\/de\/"},{"@type":"ListItem","position":2,"name":"Post-Quantum Cryptography: Jetzt auf Quantenresistenz umstellen"}]},{"@type":"WebSite","@id":"https:\/\/eperi.com\/de\/#website","url":"https:\/\/eperi.com\/de\/","name":"EPERI","description":"Empower your Data. Keep control.","publisher":{"@id":"https:\/\/eperi.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eperi.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/eperi.com\/de\/#organization","name":"EPERI","url":"https:\/\/eperi.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/eperi.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/eperi.com\/wp-content\/uploads\/2024\/07\/cropped-cropped-LogoEperi.png","contentUrl":"https:\/\/eperi.com\/wp-content\/uploads\/2024\/07\/cropped-cropped-LogoEperi.png","width":512,"height":512,"caption":"EPERI"},"image":{"@id":"https:\/\/eperi.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eperi.com\/de\/#\/schema\/person\/44a9b3a3f683b96f301707dfdd95fcff","name":"Ricardo Izzi","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g","caption":"Ricardo Izzi"},"url":"https:\/\/eperi.com\/de\/author\/ricardo-izzieperi-com\/"}]}},"_links":{"self":[{"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/posts\/11849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/comments?post=11849"}],"version-history":[{"count":5,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/posts\/11849\/revisions"}],"predecessor-version":[{"id":11855,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/posts\/11849\/revisions\/11855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/media\/11832"}],"wp:attachment":[{"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/media?parent=11849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/categories?post=11849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/tags?post=11849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}