{"id":746,"date":"2023-02-15T06:39:00","date_gmt":"2023-02-15T06:39:00","guid":{"rendered":"https:\/\/eperi.com\/?p=746"},"modified":"2025-09-17T14:35:53","modified_gmt":"2025-09-17T14:35:53","slug":"salesforce","status":"publish","type":"post","link":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/","title":{"rendered":"Wie k\u00f6nnen sensible Daten zuverl\u00e4ssig in der Salesforce Cloud gesch\u00fctzt werden?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"746\" class=\"elementor elementor-746\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-936024a e-flex e-con-boxed e-con e-parent\" data-id=\"936024a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf883d6 elementor-widget elementor-widget-tertiaryStage\" data-id=\"bf883d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tertiaryStage.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"tertiaryStage top_padding_56 \">\n\t\t\t<div>\n\t\t\t\t\t\t\t\t<h1 class=\"title_size_1 top_margin_12 teaserHeadline\">WIE K\u00d6NNEN SENSIBLE DATEN ZUVERL\u00c4SSIG IN DER SALESFORCE CLOUD GESCH\u00dcTZT WERDEN?<\/h1>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"top_margin_40 teaser-wrapper\">\n\t\t\t\t<div class=\"style-element\">\n\t\t\t\t\t<div class=\"copy_medium\" style=\"width:100%; max-width:450px\">Die Digitalisierung, neue Arbeitsmodelle sowie der starke wirtschaftliche Wandel machen es in den letzten Jahren mehr denn je erforderlich<\/div>\n\t\t\t\t\t<div class=\"top_margin_24 stageLinks\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div style=\"position:absolute; top:0px; left:0px; background-color:#00B4B4; width:4px; height:24px; border-radius: 0 0 4px 0\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"teaserImage\">\n\t\t\t\t<div><img decoding=\"async\" src=\"https:\/\/eperi.com\/wp-content\/uploads\/2024\/04\/Graphic.png\" alt=\"\" class=\"default_image border_radius_24\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-291c8785 e-flex e-con-boxed e-con e-parent\" data-id=\"291c8785\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a37c68b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5a37c68b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e8d281 e-con-full e-flex e-con e-child\" data-id=\"6e8d281\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39cd7fc0 elementor-widget elementor-widget-post-info\" data-id=\"39cd7fc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-7065232 elementor-inline-item\" itemprop=\"author\">\n\t\t\t\t\t\t<a href=\"https:\/\/eperi.com\/de\/author\/ricardo-izzieperi-com\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-pen-nib\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t\t\t\tRicardo Izzi\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-432626c elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/eperi.com\/de\/2023\/02\/15\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-calendar-alt\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>Februar 15, 2023<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-391e0d6 elementor-inline-item\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-tags\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<a href=\"https:\/\/eperi.com\/de\/category\/newsroom\/blog\/\" class=\"elementor-post-info__terms-list-item\">blog<\/a>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70aaefe6 elementor-widget elementor-widget-betterdocs-reading-time\" data-id=\"70aaefe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"betterdocs-reading-time.default\">\n\t\t\t\t\t<div class=\"reading-time betterdocs\">\n\t<p>\n\t\t<svg width=\"14\" viewBox=\"0 0 14 15\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t<mask id=\"mask0_6195_23752\" style=\"mask-type:alpha\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\">\n\t\t\t<rect y=\"0.5\" width=\"14\" height=\"14\" fill=\"#D9D9D9\"\/>\n\t\t\t<\/mask>\n\t\t\t<g mask=\"url(#mask0_6195_23752)\">\n\t\t\t<path d=\"M8.92508 10.241L9.74175 9.42435L7.58341 7.26602V4.58268H6.41675V7.73268L8.92508 10.241ZM7.00008 13.3327C6.19314 13.3327 5.4348 13.1796 4.72508 12.8733C4.01536 12.5671 3.398 12.1514 2.873 11.6264C2.348 11.1014 1.93237 10.4841 1.62612 9.77435C1.31987 9.06463 1.16675 8.30629 1.16675 7.49935C1.16675 6.6924 1.31987 5.93407 1.62612 5.22435C1.93237 4.51463 2.348 3.89727 2.873 3.37227C3.398 2.84727 4.01536 2.43164 4.72508 2.12539C5.4348 1.81914 6.19314 1.66602 7.00008 1.66602C7.80703 1.66602 8.56536 1.81914 9.27508 2.12539C9.9848 2.43164 10.6022 2.84727 11.1272 3.37227C11.6522 3.89727 12.0678 4.51463 12.374 5.22435C12.6803 5.93407 12.8334 6.6924 12.8334 7.49935C12.8334 8.30629 12.6803 9.06463 12.374 9.77435C12.0678 10.4841 11.6522 11.1014 11.1272 11.6264C10.6022 12.1514 9.9848 12.5671 9.27508 12.8733C8.56536 13.1796 7.80703 13.3327 7.00008 13.3327ZM7.00008 12.166C8.29314 12.166 9.39418 11.7115 10.3032 10.8025C11.2122 9.89345 11.6667 8.7924 11.6667 7.49935C11.6667 6.20629 11.2122 5.10525 10.3032 4.19622C9.39418 3.2872 8.29314 2.83268 7.00008 2.83268C5.70703 2.83268 4.60598 3.2872 3.69696 4.19622C2.78793 5.10525 2.33341 6.20629 2.33341 7.49935C2.33341 8.7924 2.78793 9.89345 3.69696 10.8025C4.60598 11.7115 5.70703 12.166 7.00008 12.166Z\" fill=\"#667085\"\/>\n\t\t\t<\/g>\n\t\t<\/svg>\n\t\t5 min\t<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a3556b2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3a3556b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cc01c0 e-flex e-con-boxed e-con e-parent\" data-id=\"3cc01c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4b0a11b e-con-full e-flex e-con e-child\" data-id=\"4b0a11b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-675e23a elementor-widget elementor-widget-richText\" data-id=\"675e23a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"richText.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <style>\n            .customBulletList ol {\n                list-style-type: decimal;\n                padding-left: 30px;\n            }\n\n            .customBulletList ol li {\n                padding-left: 5px;\n                margin-bottom: 16px;\n\n            }\n\n            .customBulletList ul {\n                list-style: none;\n                padding-left: 0;\n            }\n\n            .customBulletList ul li {\n                display: flex;\n                align-items: start;\n                gap: 30px;\n                margin-bottom: 16px;\n            }\n\n            .customBulletList ul li .listIcon {\n                width: 24px;\n                height: 24px;\n\n            }\n\n            .customBulletList ul li svg {\n                width: 24px !important;\n                fill: #00B4B4;\n                margin-top: 0px;\n\n            }\n\n            .customBulletList ol li .listIcon {\n                display: none !important\n            }\n\n            .customBulletList li a {\n                display: inline-flex !important;\n                text-decoration: underline !important;\n                color: #00B4B4;\n            }\n\n            .richText a {\n                color: #00B4B4;\n                text-decoration: underline;\n            }\n\n            .richText p {\n                margin: 0;\n                margin-bottom: 20px;\n            }\n\n            .richText p:last-child {\n                margin-bottom: 0 !important;\n            }\n        <\/style>\n        <div class=\"richText customBulletList copy_medium text-color\"><p>Die Digitalisierung, neue Arbeitsmodelle sowie der starke wirtschaftliche Wandel machen es in den letzten Jahren mehr denn je erforderlich, dass Gesch\u00e4ftsprozesse agil und skalierbar sind. Cloud-Dienste werden dieser Anforderung optimal gerecht und bieten eine flexible und dynamische L\u00f6sung. Im CRM-Segment ist Salesforce mit \u00fcber 20 Prozent Marktanteil weltweit unumstrittener Marktf\u00fchrer und f\u00fcr zahlreiche Unternehmen ein unentbehrlicher Bestandteil des modernen Gesch\u00e4ftslebens. Viele Abteilungen, wie zum Beispiel Vertrieb, Marketing, E\u2011Commerce und Kundenservice, k\u00f6nnen mit der cloudbasierten CRM-L\u00f6sung jederzeit und \u00fcberall zusammenarbeiten. Mit dem Gebrauch und der Aufbewahrung von sensiblen Kundendaten in der Cloud geht jedoch auch eine erhebliche Sicherheitsverantwortung einher. Sollten interne und vertrauliche Gesch\u00e4ftsinformationen, Kundenkontakte, Preislisten oder Lieferkettendetails kompromittiert werden, bringt dies weitreichende Konsequenzen f\u00fcr ein Unternehmen mit sich. <br \/>F\u00fcr Unternehmen, die Salesforce als CRM einsetzen, ist es durch den enormen Stellenwert im Unternehmen und den Umfang der sensiblen Daten zwingend erforderlich, sich mit der Sicherheit und der Compliance der Cloud-L\u00f6sung intensiv auseinanderzusetzen.<\/p><h2>WARUM VERST\u00d6SST DIE NUTZUNG VON SALESFORCE OHNE ZUS\u00c4TZLICHE SCHUTZVORKEHRUNGEN GEGEN BRANCHENSPEZIFISCHE COMPLIANCE-VORSCHRIFTEN?<\/h2><p>\u00a0<\/p><p>Salesforce ist ein US-amerikanischer Cloud-Anbieter. Die USA gelten als unsicheres Drittland im Sinne der DSGVO, da der Umgang mit personenbezogenen Daten dort nicht dem europ\u00e4ischen Stand entspricht. Zwar bietet Salesforce europ\u00e4ischen Kunden mittlerweile die M\u00f6glichkeit, ihre Daten auf Servern innerhalb der EU zu speichern, trotzdem kann es bei Verwendung mehrerer Salesforce Cloud Produkte dazu kommen, dass Daten auch auf Server au\u00dferhalb der EU transferiert werden. Ungeachtet dessen gilt der m\u00f6gliche Zugriff US-amerikanischer Administratoren auf EU-Server bereits als Drittlanddatenverkehr. Auch die Standardvertragsklauseln des Cloud-Anbieters sind keine ausreichende Vorkehrung f\u00fcr die \u00dcbermittlung sensibler Daten. Denn auch eine solche Vereinbarung mit einem US-Datenimporteur kann den legalen Zugriff durch US-Beh\u00f6rden ohne vorherigen richterlichen Beschluss nicht verhindern.<br \/>Datenschutzkonformit\u00e4t setzt den Schutz von Daten mit Personenbezug vor dem Transfer in die Cloud voraus, sofern sie in L\u00e4ndern ohne Angemessenheitsbeschluss gespeichert werden. So kann sichergestellt werden, dass US-Administratoren bei einem Zugriff sensible Daten nur verschl\u00fcsselt sehen k\u00f6nnen.<\/p><h2>BIETET SALESFORCE SHIELD KEINEN AUSREICHENDEN SCHUTZ F\u00dcR DIE SICHERE NUTZUNG DER PLATTFORM?<\/h2><p>\u00a0<\/p><p>\u00dcber die Jahre hinweg hat Salesforce seine Produktpalette stark ausgeweitet und dem prim\u00e4ren Angebot eine Reihe \u00dcber die Jahre hinweg hat Salesforce seine Produktpalette stark ausgeweitet und dem prim\u00e4ren Angebot eine Reihe integrierter Leistungen hinzugef\u00fcgt. Salesforce Shield ist ein zus\u00e4tzliches Feature des Cloud-Anbieters das die Sicherheit personenbezogener Daten gew\u00e4hrleisten soll und mit dem unter anderem Plattform-Verschl\u00fcsselung m\u00f6glich ist. Die Verschl\u00fcsselung kann dabei sowohl vom Cloud-Nutzer als auch von den Salesforce-Community Experten konfiguriert werden. Salesforce Shield Administratoren haben bei diesem Dienst jedoch trotz Verschl\u00fcsselung jederzeit Zugriff auf sensible Klardaten, denn sie kontrollieren den Schl\u00fcssel, um die Kundendaten in der Cloud zu pseudonymisieren.<\/p><p>M\u00f6chte ein Unternehmen diesen Zugriff vermeiden, dann muss die Verschl\u00fcsselung in eigener Regie vor dem Versand der Daten an den CRM-Dienst geschehen.<\/p><h2>WIE SCH\u00dcTZE ICH MEINE SENSIBLEN DATEN AM BESTEN? WAS BIETET DAS EPERI GATEWAY, DAS ANDERE ANWENDUNGEN NICHT GEW\u00c4HRLEISTEN K\u00d6NNEN?<\/h2><p>\u00a0<\/p><p>Mit der Verschl\u00fcsselung personenbezogener Daten im Datenstrom gew\u00e4hrleistet das eperi Gateway die Einhaltung der aktuellen Compliance Richtlinien im Datenschutz. Durch die Pseudonymisierung und Tokenisierung wird den Daten vor der Speicherung in der Cloud der Personenbezug entzogen und unsere Kunden agieren datenschutzkonform. Das eperi Gateway hat keine Auswirkungen auf die Kompatibilit\u00e4t zwischen unterschiedlichen Anwendungen. Im Gegenteil, es kann dazu beitragen, die Nutzung von Schatten-IT zu verhindern und schwerwiegende Sicherheitsl\u00fccken zu vermeiden. Mit unserer L\u00f6sung bleibt Ihre Unabh\u00e4ngigkeit und Selbstbestimmung erhalten. Mithilfe der selektiven Verschl\u00fcsselung kann das eperi Gateway feld- und inhaltsbasiert flexibel personenbezogene Daten verschl\u00fcsseln. Schl\u00fcssel und Verschl\u00fcsselung bleiben jederzeit unter Ihrer alleinigen Kontrolle. So bleibt viel Spielraum f\u00fcr individuelle Konfigurationen. Die IT-Infrastruktur bleibt durch die nahtlose Integration uneingeschr\u00e4nkt und es kommen keine Latenzen bei der Nutzung der Anwendung vor. Durch die funktionserhaltende Verschl\u00fcsselung von eperi k\u00f6nnen Funktionen wie Suche, Sortierung, Filter und Regeln weiterhin uneingeschr\u00e4nkt genutzt werden. Diese Funktionen stehen beim Einsatz von Salesforce Shield nicht mehr zur Verf\u00fcgung. Auch die datenzentrierte Verschl\u00fcsselung und Tokenisierung auf Feldebene, sowie die Pseudonymisierung unstrukturierter Daten, insbesondere von Dateien ist bei der Nutzung von Cloud-Anwendungen keine Selbstverst\u00e4ndlichkeit. Selbst bei einem Datendiebstahl bleiben sensible Daten auf diese Weise sicher gesch\u00fctzt, da der Angreifer die verschl\u00fcsselten Daten nicht verwenden kann.<\/p><h2>IST ES NICHT DIE AUFGABE VON SALESFORCE, SICH UM DIE SICHERHEIT IHRER ANWENDUNG ZU K\u00dcMMERN?<\/h2><p>\u00a0<\/p><p>Im Rahmen des \u201eShared Responsibility\u201c Models m\u00fcssen Cloud-Anwender ihren Anteil zur Sicherheit von sensiblen Daten in der Cloud beitragen. Sie k\u00f6nnen sich nicht darauf verlassen, dass ihr Cloud-Anbieter f\u00fcr die Sicherheit ihrer Daten sorgt. Viele Unternehmen sind sich dieser Verantwortung nicht bewusst. <br \/>Dabei regelt das Modell der gemeinsamen Verantwortung als Sicherheits- und Compliance-Framework ganz klar die Verantwortungsbereiche von Cloud Service Provider und SaaS-Anbietern sowie Kunden bei der Absicherung aller Aspekte der Cloud-Umgebung. Dies beinhaltet unter anderem Hardware, Infrastruktur, Endger\u00e4te und Betriebssysteme, aber auch die in den Systemen gespeicherten Daten. Einfach ausgedr\u00fcckt legt das Modell fest welcher Vertragspartner die Sicherheitsvorkehrungen f\u00fcr bestimmte Komponenten \u00fcbernehmen muss. Der Cloud-Anbieter ist verantwortlich f\u00fcr die \u00dcberwachung und Abwehr von Sicherheitsbedrohungen, die die Cloud selbst und die grundlegende Infrastruktur angreifen. Cloud-Nutzer sind dazu verpflichtet die Daten und andere in der Cloud-Umgebung gespeicherte Assets zu sch\u00fctzen. Nur wenn beide Vertragspartner ihre Aufgabe ernst nehmen und sich um ihren Teil der gemeinsamen Verantwortung k\u00fcmmern, ist ein ganzheitlicher Sicherheitsansatz gew\u00e4hrleistet.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f6d89dd e-con-full e-flex e-con e-child\" data-id=\"5f6d89dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-295b20be elementor-widget elementor-widget-richText\" data-id=\"295b20be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"richText.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <style>\n            .customBulletList ol {\n                list-style-type: decimal;\n                padding-left: 30px;\n            }\n\n            .customBulletList ol li {\n                padding-left: 5px;\n                margin-bottom: 16px;\n\n            }\n\n            .customBulletList ul {\n                list-style: none;\n                padding-left: 0;\n            }\n\n            .customBulletList ul li {\n                display: flex;\n                align-items: start;\n                gap: 30px;\n                margin-bottom: 16px;\n            }\n\n            .customBulletList ul li .listIcon {\n                width: 24px;\n                height: 24px;\n\n            }\n\n            .customBulletList ul li svg {\n                width: 24px !important;\n                fill: #00B4B4;\n                margin-top: 0px;\n\n            }\n\n            .customBulletList ol li .listIcon {\n                display: none !important\n            }\n\n            .customBulletList li a {\n                display: inline-flex !important;\n                text-decoration: underline !important;\n                color: #00B4B4;\n            }\n\n            .richText a {\n                color: #00B4B4;\n                text-decoration: underline;\n            }\n\n            .richText p {\n                margin: 0;\n                margin-bottom: 20px;\n            }\n\n            .richText p:last-child {\n                margin-bottom: 0 !important;\n            }\n        <\/style>\n        <div class=\"richText customBulletList copy_medium text-color\"><h2>Hat Ihnen dieser Artikel gefallen?<\/h2><p>Dann jetzt liken oder mit Kollegen, Gesch\u00e4ftspartnern sowie Freunden teilen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13204e0f e-grid e-con-full e-con e-child\" data-id=\"13204e0f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1dcea0c0 elementor-share-buttons--shape-rounded elementor-share-buttons--view-icon-text elementor-share-buttons--skin-gradient elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"1dcea0c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Share on email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Share on facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Share on linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_x-twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Share on x-twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-x-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tX\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-564c5206 elementor-widget elementor-widget-shortcode\" data-id=\"564c5206\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div class=\"wpulike wpulike-default \" ><div class=\"wp_ulike_general_class wp_ulike_is_restricted\"><button type=\"button\"\n\t\t\t\t\taria-label=\"Like Button\"\n\t\t\t\t\tdata-ulike-id=\"746\"\n\t\t\t\t\tdata-ulike-nonce=\"8d1519391f\"\n\t\t\t\t\tdata-ulike-type=\"post\"\n\t\t\t\t\tdata-ulike-template=\"wpulike-default\"\n\t\t\t\t\tdata-ulike-display-likers=\"0\"\n\t\t\t\t\tdata-ulike-likers-style=\"default\"\n\t\t\t\t\tclass=\"wp_ulike_btn wp_ulike_put_image wp_post_btn_746\"><\/button><span class=\"count-box wp_ulike_counter_up\" data-ulike-counter-value=\"0\"><\/span>\t\t\t<\/div><\/div>\n\t\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-144ae3eb e-flex e-con-boxed e-con e-parent\" data-id=\"144ae3eb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4f7c2f06 e-grid e-con-boxed e-con e-child\" data-id=\"4f7c2f06\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-66ba9794 e-con-full e-flex e-con e-child\" data-id=\"66ba9794\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4236ea5 elementor-widget elementor-widget-h2\" data-id=\"4236ea5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"h2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <!-- <div style=\"background-color:red; color:white; display:inline; padding:0px 5px\">H2 Headline<\/div> -->\n        <h2 class=\"title_size_2 headline-color\">Wissen, das sch\u00fctzt \u2013 Ihre n\u00e4chste Ma\u00dfnahme f\u00fcr mehr Datensicherheit<\/h2>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43f928ff elementor-widget elementor-widget-richText\" data-id=\"43f928ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"richText.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\n        <style>\n            .customBulletList ol {\n                list-style-type: decimal;\n                padding-left: 30px;\n            }\n\n            .customBulletList ol li {\n                padding-left: 5px;\n                margin-bottom: 16px;\n\n            }\n\n            .customBulletList ul {\n                list-style: none;\n                padding-left: 0;\n            }\n\n            .customBulletList ul li {\n                display: flex;\n                align-items: start;\n                gap: 30px;\n                margin-bottom: 16px;\n            }\n\n            .customBulletList ul li .listIcon {\n                width: 24px;\n                height: 24px;\n\n            }\n\n            .customBulletList ul li svg {\n                width: 24px !important;\n                fill: #00B4B4;\n                margin-top: 0px;\n\n            }\n\n            .customBulletList ol li .listIcon {\n                display: none !important\n            }\n\n            .customBulletList li a {\n                display: inline-flex !important;\n                text-decoration: underline !important;\n                color: #00B4B4;\n            }\n\n            .richText a {\n                color: #00B4B4;\n                text-decoration: underline;\n            }\n\n            .richText p {\n                margin: 0;\n                margin-bottom: 20px;\n            }\n\n            .richText p:last-child {\n                margin-bottom: 0 !important;\n            }\n        <\/style>\n        <div class=\"richText customBulletList copy_medium text-color\"><p>Auf unserer Download-Seite finden Sie kostenlose Whitepaper und Factsheets zu Datenschutz, Datenverschl\u00fcsselung und Compliance \u2013 speziell f\u00fcr IT-Verantwortliche und Entscheider.<br data-start=\"416\" data-end=\"419\" \/><br \/>Erhalten Sie kompaktes Wissen, strategische Empfehlungen und praktische Tipps, um Ihre Daten effektiv zu sch\u00fctzen und regulatorische Vorgaben wie DSGVO, NIS2 und DORA sicher zu erf\u00fcllen.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17ee1103 elementor-widget elementor-widget-primaryButton\" data-id=\"17ee1103\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"primaryButton.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n                    <div class=\"button button_light_primary\">\n                                <a href=\"https:\/\/eperi.com\/de\/info-hub\/downloads\/\" class=\"button_link\" id=\"\">\n                    Jetzt informieren &amp; kostenlos herunterladen                <\/a>\n            <\/div>\n        \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-761ad7f elementor-widget elementor-widget-image\" data-id=\"761ad7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<!-- <div style=\"background-color:red; color:white; display:inline; padding:0px 5px\">Image<\/div> -->\n\t\t<img decoding=\"async\" src=\"https:\/\/eperi.com\/wp-content\/uploads\/2025\/04\/Whitepaper_Ganzheitliche_Cloud_Datenschutz_A4_Brochure_Mockup_2-scaled.jpg\" alt=\"\" class=\"default_image border_radius_24\">\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Die Digitalisierung, neue Arbeitsmodelle sowie der starke wirtschaftliche Wandel machen es in den letzten Jahren mehr denn je erforderlich<\/p>\n","protected":false},"author":6,"featured_media":2261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sensible Daten zuverl\u00e4ssig in der Salesforce Cloud sch\u00fctzen<\/title>\n<meta name=\"description\" content=\"Sch\u00fctzen Sie sensible Daten in der Salesforce Cloud zuverl\u00e4ssig und compliance-konform mit dem eperi Gateway. Erfahren Sie, wie unsere L\u00f6sung Ihre Daten sichert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sensible Daten zuverl\u00e4ssig in der Salesforce Cloud sch\u00fctzen\" \/>\n<meta property=\"og:description\" content=\"Sch\u00fctzen Sie sensible Daten in der Salesforce Cloud zuverl\u00e4ssig und compliance-konform mit dem eperi Gateway. Erfahren Sie, wie unsere L\u00f6sung Ihre Daten sichert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/\" \/>\n<meta property=\"og:site_name\" content=\"EPERI\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-15T06:39:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-17T14:35:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eperi.com\/wp-content\/uploads\/2024\/02\/Newsroom_Blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Izzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Izzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/\"},\"author\":{\"name\":\"Ricardo Izzi\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#\\\/schema\\\/person\\\/44a9b3a3f683b96f301707dfdd95fcff\"},\"headline\":\"Wie k\u00f6nnen sensible Daten zuverl\u00e4ssig in der Salesforce Cloud gesch\u00fctzt werden?\",\"datePublished\":\"2023-02-15T06:39:00+00:00\",\"dateModified\":\"2025-09-17T14:35:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/\"},\"wordCount\":1059,\"publisher\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Newsroom_Blog.jpg\",\"articleSection\":[\"blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/\",\"url\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/\",\"name\":\"Sensible Daten zuverl\u00e4ssig in der Salesforce Cloud sch\u00fctzen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Newsroom_Blog.jpg\",\"datePublished\":\"2023-02-15T06:39:00+00:00\",\"dateModified\":\"2025-09-17T14:35:53+00:00\",\"description\":\"Sch\u00fctzen Sie sensible Daten in der Salesforce Cloud zuverl\u00e4ssig und compliance-konform mit dem eperi Gateway. Erfahren Sie, wie unsere L\u00f6sung Ihre Daten sichert.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Newsroom_Blog.jpg\",\"contentUrl\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Newsroom_Blog.jpg\",\"width\":1200,\"height\":800,\"caption\":\"diverse Tasten einer Tastatur liegen auf dem Tisch verteilt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/newsroom\\\/blog\\\/salesforce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/eperi.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie k\u00f6nnen sensible Daten zuverl\u00e4ssig in der Salesforce Cloud gesch\u00fctzt werden?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/eperi.com\\\/de\\\/\",\"name\":\"EPERI\",\"description\":\"Empower your Data. Keep control.\",\"publisher\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eperi.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#organization\",\"name\":\"EPERI\",\"url\":\"https:\\\/\\\/eperi.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-cropped-LogoEperi.png\",\"contentUrl\":\"https:\\\/\\\/eperi.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-cropped-LogoEperi.png\",\"width\":512,\"height\":512,\"caption\":\"EPERI\"},\"image\":{\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eperi.com\\\/de\\\/#\\\/schema\\\/person\\\/44a9b3a3f683b96f301707dfdd95fcff\",\"name\":\"Ricardo Izzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g\",\"caption\":\"Ricardo Izzi\"},\"url\":\"https:\\\/\\\/eperi.com\\\/de\\\/author\\\/ricardo-izzieperi-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sensible Daten zuverl\u00e4ssig in der Salesforce Cloud sch\u00fctzen","description":"Sch\u00fctzen Sie sensible Daten in der Salesforce Cloud zuverl\u00e4ssig und compliance-konform mit dem eperi Gateway. Erfahren Sie, wie unsere L\u00f6sung Ihre Daten sichert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/","og_locale":"de_DE","og_type":"article","og_title":"Sensible Daten zuverl\u00e4ssig in der Salesforce Cloud sch\u00fctzen","og_description":"Sch\u00fctzen Sie sensible Daten in der Salesforce Cloud zuverl\u00e4ssig und compliance-konform mit dem eperi Gateway. Erfahren Sie, wie unsere L\u00f6sung Ihre Daten sichert.","og_url":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/","og_site_name":"EPERI","article_published_time":"2023-02-15T06:39:00+00:00","article_modified_time":"2025-09-17T14:35:53+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/eperi.com\/wp-content\/uploads\/2024\/02\/Newsroom_Blog.jpg","type":"image\/jpeg"}],"author":"Ricardo Izzi","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Ricardo Izzi","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/#article","isPartOf":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/"},"author":{"name":"Ricardo Izzi","@id":"https:\/\/eperi.com\/de\/#\/schema\/person\/44a9b3a3f683b96f301707dfdd95fcff"},"headline":"Wie k\u00f6nnen sensible Daten zuverl\u00e4ssig in der Salesforce Cloud gesch\u00fctzt werden?","datePublished":"2023-02-15T06:39:00+00:00","dateModified":"2025-09-17T14:35:53+00:00","mainEntityOfPage":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/"},"wordCount":1059,"publisher":{"@id":"https:\/\/eperi.com\/de\/#organization"},"image":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/#primaryimage"},"thumbnailUrl":"https:\/\/eperi.com\/wp-content\/uploads\/2024\/02\/Newsroom_Blog.jpg","articleSection":["blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/","url":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/","name":"Sensible Daten zuverl\u00e4ssig in der Salesforce Cloud sch\u00fctzen","isPartOf":{"@id":"https:\/\/eperi.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/#primaryimage"},"image":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/#primaryimage"},"thumbnailUrl":"https:\/\/eperi.com\/wp-content\/uploads\/2024\/02\/Newsroom_Blog.jpg","datePublished":"2023-02-15T06:39:00+00:00","dateModified":"2025-09-17T14:35:53+00:00","description":"Sch\u00fctzen Sie sensible Daten in der Salesforce Cloud zuverl\u00e4ssig und compliance-konform mit dem eperi Gateway. Erfahren Sie, wie unsere L\u00f6sung Ihre Daten sichert.","breadcrumb":{"@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/#primaryimage","url":"https:\/\/eperi.com\/wp-content\/uploads\/2024\/02\/Newsroom_Blog.jpg","contentUrl":"https:\/\/eperi.com\/wp-content\/uploads\/2024\/02\/Newsroom_Blog.jpg","width":1200,"height":800,"caption":"diverse Tasten einer Tastatur liegen auf dem Tisch verteilt"},{"@type":"BreadcrumbList","@id":"https:\/\/eperi.com\/de\/newsroom\/blog\/salesforce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/eperi.com\/de\/"},{"@type":"ListItem","position":2,"name":"Wie k\u00f6nnen sensible Daten zuverl\u00e4ssig in der Salesforce Cloud gesch\u00fctzt werden?"}]},{"@type":"WebSite","@id":"https:\/\/eperi.com\/de\/#website","url":"https:\/\/eperi.com\/de\/","name":"EPERI","description":"Empower your Data. Keep control.","publisher":{"@id":"https:\/\/eperi.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eperi.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/eperi.com\/de\/#organization","name":"EPERI","url":"https:\/\/eperi.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/eperi.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/eperi.com\/wp-content\/uploads\/2024\/07\/cropped-cropped-LogoEperi.png","contentUrl":"https:\/\/eperi.com\/wp-content\/uploads\/2024\/07\/cropped-cropped-LogoEperi.png","width":512,"height":512,"caption":"EPERI"},"image":{"@id":"https:\/\/eperi.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eperi.com\/de\/#\/schema\/person\/44a9b3a3f683b96f301707dfdd95fcff","name":"Ricardo Izzi","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ff0a1928369c96643a7d20b43dbb811724e991a5def7ec8ebd4039552cfa154?s=96&d=mm&r=g","caption":"Ricardo Izzi"},"url":"https:\/\/eperi.com\/de\/author\/ricardo-izzieperi-com\/"}]}},"_links":{"self":[{"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/posts\/746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/comments?post=746"}],"version-history":[{"count":23,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/posts\/746\/revisions"}],"predecessor-version":[{"id":11917,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/posts\/746\/revisions\/11917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/media\/2261"}],"wp:attachment":[{"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/media?parent=746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/categories?post=746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eperi.com\/de\/wp-json\/wp\/v2\/tags?post=746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}